{"id":96591,"date":"2020-09-15T11:25:26","date_gmt":"2020-09-15T11:25:26","guid":{"rendered":"https:\/\/herway.net\/?p=96591"},"modified":"2022-01-20T20:39:04","modified_gmt":"2022-01-20T20:39:04","slug":"poesie-damore-per-la-moglie","status":"publish","type":"post","link":"https:\/\/herway.net\/it\/poesie-damore-per-la-moglie\/","title":{"rendered":"Una raccolta di poesie d'amore incredibilmente romantiche per la moglie"},"content":{"rendered":"<p>Avete mai pensato a quanto possano essere speciali le poesie d'amore per la moglie?<\/p>\n<p>Non solo urlano<em> Ti amo<\/em>, but they also show your wife that you&#8217;re still a romantic at heart!<\/p>\n<p>To help you find just the right words, I&#8217;ve compiled a collection of<a href=\"https:\/\/herway.net\/it\/top-40-belle-poesie-per-lei-direttamente-dal-cuore\/\"> poesie romantiche<\/a>, short love poems, I love you poems \u2013 all in all, some of the best love poems you&#8217;ll ever encounter.<\/p>\n<p>Credo fermamente che l'impegno non passi mai di moda e la vostra anima gemella apprezzer\u00e0 profondamente questo gesto incredibilmente romantico.<\/p>\n<p>Utilizzate questi famosi <a href=\"https:\/\/herway.net\/it\/poesie-damore-per-lui\/\">poesie d'amore per dimostrare l'amore della tua vita<\/a> that you&#8217;ll never stop trying.<\/p>\n<p>It doesn&#8217;t have to be Valentine&#8217;s Day to do something special for her.<\/p>\n<p>Pi\u00f9 il giorno \u00e8 ordinario, pi\u00f9 il gesto \u00e8 significativo.<\/p>\n<p>Sending your wife love poems will be something she&#8217;ll never expect, yet thoroughly enjoy.<\/p>\n<p><strong>Senza ulteriori indugi, ecco alcune poesie d'amore per la moglie davvero carine che dimostrano che le vere storie d'amore non finiscono mai.<\/strong><\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/sentirsi-non-amati-2\/\" target=\"_blank\" rel=\"noopener noreferrer\">Vi sentite poco amati? Ecco i possibili motivi e come cambiarli<\/a><\/p>\n<h2 class=\"numbered-headline\">A Woman&#8217;s Hand<\/h2>\n<p><em>di Amos Russel Wells<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96664\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands.jpg\" alt=\"due mani di donna sopra i palmi aperti\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/womans-two-hands-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Morbido e tenero, liscio e bianco,<br \/>\nFormata per vincere e deliziare,<br \/>\nNature has no lovelier sight,\u2014<br \/>\nA woman\u2019s hand.<\/p>\n<p>Stropicciato, usurato, con molto da fare,<br \/>\nMolti compiti per me e per voi,<br \/>\nIn all trials good and true,\u2014<br \/>\nA woman\u2019s hand.<\/p>\n<p>Stringendo le nostre attraverso la vita e la morte,<br \/>\nAmorevolmente all'ultimo respiro,<br \/>\nThe sweetest thing that comforteth,\u2014<br \/>\nA woman\u2019s hand.<\/p>\n<h2 class=\"numbered-headline\">Tu, mia moglie, mio tesoro<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96667\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple.jpg\" alt=\"giovane coppia ispanica donna seduta sulle ginocchia dell&#039;uomo seduto su una sedia d&#039;albergo\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-hispanic-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Avevo attraversato la vita senza nulla fino a te; fino a te non conoscevo il piacere.<br \/>\nE poi un giorno Dio mi ha mandato te: tu, mia moglie, il mio tesoro.<br \/>\nUn dono di Dio, un dono cos\u00ec bello che non potr\u00e0 mai essere misurato.<br \/>\nA love so fine, so sweet, so kind; it\u2019s you, my love; you, my wife, my treasure.<\/p>\n<p>Prometto di abbracciarti, baciarti e stringerti ogni giorno.<br \/>\nPrometto un amore con una devozione che non svanir\u00e0 mai.<br \/>\nPrometto e giuro davanti a Dio<br \/>\nPer mostrarti solo il mio amore puro.<\/p>\n<p>Ammirer\u00f2 la benedizione del vostro amore sconfinato,<br \/>\nPerch\u00e9 so che siete un vero dono del cielo.<br \/>\nNon vi far\u00f2 del male con le mie frustrazioni.<br \/>\nTi stringer\u00f2 a me e ti bacer\u00f2 con amorevole ammirazione.<\/p>\n<p>Apprezzer\u00f2 sempre il vostro impegno nei miei confronti.<br \/>\nGive me a chance, for can\u2019t you see?<br \/>\nNon si tratta di un gioco d'azzardo.<br \/>\n\u00c8 un amore vero che giuro si impegna a rimanere.<\/p>\n<p>Lei dice che a volte ha paura.<br \/>\nQuesta volta non riesco a trovare una rima, quindi permettetemi di essere chiaro:<\/p>\n<p>I will\u2026<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Ti amo infinitamente<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Dedicare la mia vita a renderti felice<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Ammirarvi ogni giorno per la persona che siete<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Interessatevi alle cose che vi piacciono.<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Ammirate ogni giorno con stupore la vostra bellezza e riflettetela su di voi.<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Essere attenti a voi e alle vostre esigenze<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Essere indulgenti<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Listen to you with never a harsh word in return (I swear it and pray for it in God\u2019s name)<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Dimostrarti con le mie azioni che ti amo<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Essere pi\u00f9 aperti e divertenti con voi, la vostra famiglia e i vostri amici.<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Non andare mai a letto senza di te<br \/>\n&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Strofinarvi, baciarvi, farvi il bagno, tirarvi su, o qualsiasi cosa sia necessaria quando vi sentite gi\u00f9.<\/p>\n<p>Ti bacer\u00f2 e ti amer\u00f2 quanto pi\u00f9 possibile,<br \/>\nAnd don\u2019t be embarrassed to be seen holding my hand.<br \/>\nFar\u00f2 tesoro di ogni giorno come se fosse l'ultimo,<br \/>\nAnd at the end of your life, you won\u2019t regret me being your past.<\/p>\n<p>Sei il sole del mio mattino e, come un uccello, ti canter\u00f2 una canzone.<br \/>\nI know that in this life when I am troubled, through God it\u2019s you who keeps me strong.<\/p>\n<p>Tu sei la madre dei miei figli e l'aria che mi d\u00e0 la vita,<br \/>\nLa mia amica pi\u00f9 vera di tutte, il mio cuore, la mia anima, mia moglie.<\/p>\n<p>Ti amo molto; sei tutto ci\u00f2 che di buono c'\u00e8 in questo mondo.<\/p>\n<h2 class=\"numbered-headline\">Una buona donna<\/h2>\n<p><em>di Carol Naumann<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96668\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying.jpg\" alt=\"bella donna sdraiata su camera da letto bianca sorridente\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautitiful-woman-lying-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Un oggetto da custodire, ma non da possedere,<br \/>\nChe ha bisogno di essere amato, non trattato con aggressivit\u00e0.<br \/>\nHer value is more than all the world\u2019s treasures,<br \/>\nNot just the sum of the scale\u2019s unit measures.<br \/>\nDeve sempre essere costruita, non abbattuta,<br \/>\nDa tutte le parole che pronunciate, quando lei \u00e8 nei paraggi.<br \/>\nHa bisogno di essere abbracciata e non allontanata,<br \/>\nSoprattutto quando entrambi state passando una brutta giornata.<br \/>\nParole pronunciate in fretta e furia<br \/>\nPu\u00f2 mettere in pericolo il suo fragile cuore.<br \/>\nDovrebbe essere ammirata per il suo amore sconfinato,<br \/>\nE guardate come un vero dono dall'Alto.<br \/>\nNon utilizzate come bersaglio per tutta la vostra frustrazione,<br \/>\nMa tenuta stretta e baciata con amorevole ammirazione.<br \/>\nDovreste sempre apprezzare il suo impegno nei vostri confronti,<br \/>\nAnd not take for granted what she\u2019s given up for you!<br \/>\nBaciatela e amatela quanto pi\u00f9 possibile,<br \/>\nAnd don\u2019t be embarrassed to be seen holding her hand.<br \/>\nFate tesoro di ogni giorno come se fosse l'ultimo,<br \/>\nAnd at the end of your life, you won\u2019t be regretting your past.<\/p>\n<h2 class=\"numbered-headline\">Una promessa a mia moglie<\/h2>\n<p><em>di Sean Short<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96669\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man.jpg\" alt=\"foto ravvicinata di un uomo che fa il cavalluccio a una donna all&#039;aperto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/closeup-photo-of-a-man-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p><strong>Speranza<\/strong><\/p>\n<p>I promise to have hope when we\u2019ve strayed off the path<br \/>\nTo know in my heart and accept God\u2019s wrath<br \/>\nChe le cose che Egli fa non sono crudeli.<br \/>\nBut to make us realize that we\u2019ve acted a fool<br \/>\nSostituire tutte le nostre paure e i nostri dubbi con la speranza<br \/>\nWhen we feel we\u2019re at the end of our rope<br \/>\nLa guarigione richiede tempo, ma \u00e8 bene tornare sulla strada giusta.<br \/>\nI will be waiting for you when you\u2019re ready to come back<\/p>\n<p><strong>La fede<\/strong><\/p>\n<p>Prometto di avere fede in Te, in Noi e in Dio.<br \/>\nHa colpito il mio cuore e la mia anima come un parafulmine<br \/>\nLa fede \u00e8 la forza che render\u00e0 forte il nostro rapporto di coppia<br \/>\nFa s\u00ec che il mio amore per te si prolunghi per sempre<br \/>\nLa fede \u00e8 qualcosa su cui possiamo contare quando ci sentiamo perduti.<br \/>\nNon dobbiamo mai dubitarne, a qualunque costo<br \/>\nQuando troviamo la vera fede, possiamo trovare il vero Amore.<br \/>\nTutto ci\u00f2 che dobbiamo fare \u00e8 confidare nel Signore sopra di noi.<\/p>\n<p><strong>L'amore<\/strong><\/p>\n<p>Prometto di amarti nella buona e nella cattiva sorte.<br \/>\nI\u2019ll love you when I\u2019m angry, hurt and mad<br \/>\nLove is a choice I\u2019ve made to devote my life<br \/>\nPer fare di te, Michelle, il mio mondo, mia moglie<br \/>\nNothing will ever change that choice that I\u2019ve made<br \/>\nAnche quando sentiamo che il nostro amore comincia a svanire<br \/>\nIt\u2019s inside my soul, and nothing can shake<br \/>\nMy Love for you, that\u2019s a promise I won\u2019t break<\/p>\n<h2 class=\"numbered-headline\">Nike<\/h2>\n<p><em>di Bliss Carman<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96670\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen.jpg\" alt=\"giovane donna con una protezione solare a forma di sole sulla spalla\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-woman-with-a-sunscreen-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Per cosa ringraziano gli uomini?<br \/>\nNe ringrazio uno,<br \/>\nPi\u00f9 bella del mattino,<br \/>\nPi\u00f9 caro del sole.<\/p>\n<p>Una testa cos\u00ec i vincitori<br \/>\nDeve aver lodato e conosciuto,<br \/>\nCon quel seno e quel portamento,<br \/>\nNike\u2019s very own\u2014<\/p>\n<p>Come superba, senza ostacoli,<br \/>\nRitmato, in bilico e libero<br \/>\nCome il forte e puro vento di mare<br \/>\nCamminare sul mare;<\/p>\n<p>Una mano come la Bellezza<br \/>\nUtilizza con tutto il cuore,<br \/>\nAlla ricerca della sua libert\u00e0<br \/>\nIn nuove forme d'arte;<\/p>\n<p>Morbido come la pioggia in aprile,<br \/>\nTranquillo come i giorni<br \/>\nDegli astri viola<br \/>\nE la foschia autunnale;<\/p>\n<p>Con un'anima pi\u00f9 sottile<br \/>\ndella luce delle stelle,<br \/>\nFrailer than a moth\u2019s wing<br \/>\nAl tatto che si fa marsina;<\/p>\n<p>Saggio con tutto il silenzio<br \/>\nDelle colline in attesa,<br \/>\nQuando il grazioso crepuscolo<br \/>\nSi sveglia in loro e si emoziona;<\/p>\n<p>Con una voce pi\u00f9 tenera<br \/>\ndella luna presto<br \/>\nSi sente tra i tordi<br \/>\nNei boschi di giugno;<\/p>\n<p>Delicati come l'erba<br \/>\nWhen they lift and stir \u2014<br \/>\nOne sweet lyric woman\u2014<br \/>\nRingrazio per lei.<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/la-mia-anima-e-stanca\/\" target=\"_blank\" rel=\"noopener noreferrer\">La mia anima \u00e8 stanca: Riconoscere i segni della stanchezza dell'anima e risolverla<\/a><\/p>\n<h2 class=\"numbered-headline\">Il gusto dell'amore<\/h2>\n<p><em>by Sean O&#8217;Brien<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96673\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand.jpg\" alt=\"coppia di donne che si tengono per mano con un uomo che viaggia vicino alla montagna e a uno specchio d&#039;acqua\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-woman-holding-hand-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mia moglie<br \/>\nBellezza e grazia<br \/>\nUn sorriso sul mio viso<br \/>\nUna mano da stringere<br \/>\nUn compagno per invecchiare<br \/>\nUn mix di risate e lacrime sulle spalle<br \/>\nPossiamo invecchiare, ma il nostro amore non riflette gli anni<br \/>\nMi hai dato tutto nella vita che vedo come buona<br \/>\nMi ha fatto sognare cose che non avrei mai pensato di poter sognare.<br \/>\nIl mio pilastro di forza nel profondo della mia anima<br \/>\nColui che ha reso la mia vita completa<br \/>\nBellezza indescrivibile dentro e fuori<br \/>\nL'amore che riflettete getta ombra su ogni mio dubbio<br \/>\nLo sguardo nei tuoi occhi mi fa battere il cuore<br \/>\nEver since I meet you I\u2019ve enjoyed this trip<br \/>\nQuindi a te, amore mio, ti ringrazio tanto<br \/>\nE prego che la fine del mio amore non si conosca mai<\/p>\n<h2 class=\"numbered-headline\">Innamorato di te<\/h2>\n<p><em>di David Yearwood<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96676\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple.jpg\" alt=\"ritratto di giovane coppia innamorata che si guarda negli occhi sorridendo \" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/portrait-of-a-young-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>I\u2019m happy I\u2019m the one, to be in love with you,<br \/>\nI want to scream my lungs, till I\u2019m blue,<br \/>\nVoglio che il mondo sappia che ho te.<br \/>\nCome sono felice di essere innamorato di te,<\/p>\n<p>Come sono fortunato, mi sento amato da voi,<br \/>\nLa mia mente \u00e8 in preda ai pensieri di te,<br \/>\nquando si tratta di romanticismo, penso a te<br \/>\nYou\u2019re my passion and desire, in all, I\u2019m yours,<\/p>\n<p>Ogni pulsazione del mio corpo brucia come un fuoco rosso.<br \/>\nAttraversa il mio cuore come una profonda gola,<br \/>\nquando sorridi, mi vengono i brividi,<br \/>\nI\u2019m swept off my feet, like a breeze from the sky.<\/p>\n<p>Le mie emozioni sono selvagge e mi prendono il sopravvento,<br \/>\nsuddenly, life is better, cause, I\u2019m in love with you!<\/p>\n<h2 class=\"numbered-headline\">A te, lo prometto<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96677\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising.jpg\" alt=\"coppia di sposi promettente uomo che tiene la mano della donna che porta un buoquet di fiori\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/wedding-couple-promising-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Il mio amore per te \u00e8 incondizionato e duraturo.<br \/>\nA voi prometto di essere sempre rassicurante.<\/p>\n<p>Il mio amore per voi vi protegge ed \u00e8 onorevole.<br \/>\nA te prometto di essere sempre fedele.<\/p>\n<p>Il mio amore per te \u00e8 comprensivo e appassionato.<br \/>\nA voi prometto di essere sempre compassionevole.<\/p>\n<p>Il mio amore per te \u00e8 premuroso e amorevole.<br \/>\nA te prometto di essere sempre devoto e premuroso.<\/p>\n<p>Il mio amore per voi \u00e8 paziente e gentile.<br \/>\nA te, lo prometto sempre fino alla fine dei tempi.<\/p>\n<p>Il mio amore per voi \u00e8 disinteressato e perdonante.<br \/>\nA voi, lo prometto sempre, finch\u00e9 sar\u00f2 in vita.<\/p>\n<p>Il mio amore per voi \u00e8 devoto e incoraggiante.<br \/>\nA voi, prometto di ascoltare sempre e di non deviare mai.<\/p>\n<p>Prometto di dimostrarti, moglie mia, che ti amo in tutto ci\u00f2 che faccio.<br \/>\nPosso promettere queste cose perch\u00e9 con tutto il mio cuore vi amo.<\/p>\n<h2 class=\"numbered-headline\">A mia moglie<\/h2>\n<p><em>di Amos Russel Wells<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96681\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset.jpg\" alt=\"Coppia che si gode il tramonto seduti sulla piattaforma di legno sul mare\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-enjoying-sunset-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Due nuvole che fluttuano insieme per tutto il giorno<br \/>\n&nbsp; Insieme ai corsi di sole del cielo,<br \/>\n&nbsp; Will sadly part, as day\u2019s enchantments die,<br \/>\nAnd perish in the twilight\u2019s common gray.<br \/>\nDue rivoli, che trovano una strada comune,<br \/>\n&nbsp; E carol molti paesaggi splendenti,<br \/>\n&nbsp; Scendere finalmente dove giacciono le acque senza nome<br \/>\nBeneath the ocean\u2019s all-dissolving sway,<br \/>\nNon molto, cara moglie, cara amante, \u00e8 l'obiettivo<br \/>\n&nbsp; That waits for us upon our final breath, \u2014<br \/>\n&nbsp; Due bolle, schiacciate in un vortice di schiuma;<br \/>\nMa come due pellegrini, logorati nel senso e nell'anima,<br \/>\n&nbsp; Come saremo felici quando la gentile Morte<br \/>\n&nbsp; Punta le luci e le porte aperte di casa!<\/p>\n<h2 class=\"numbered-headline\">Quando i complimenti pagano di pi\u00f9<\/h2>\n<p><em>di Amos Russel Wells<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96688\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple.jpg\" alt=\"coppia dolce e fredda che si abbraccia nel parco d&#039;autunno\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-old-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Tua moglie sta invecchiando, amico,<br \/>\nIl bianco \u00e8 nei suoi capelli,<br \/>\nMa \u00e8 bello da vedere, amico,<br \/>\nCome quando una fanciulla bella.<\/p>\n<p>For there\u2019s an autumn beauty<br \/>\nPi\u00f9 affascinante della primavera;<br \/>\nLa grazia dell'amore e del dovere,<br \/>\n\u00c8 una cosa meravigliosa!<\/p>\n<p>Then tell your wife \u2019tis so, man,\u2014<br \/>\nIt\u2019s better lore than books,\u2014<br \/>\nPerch\u00e9 alle donne piace sapere, amico,<br \/>\nChe agli uomini piace ancora il loro aspetto.<\/p>\n<p>E forse ve lo dir\u00e0,<br \/>\nFor she\u2019s a guileful tongue,<br \/>\nGli anni ti incantano cos\u00ec gentilmente<br \/>\nChe sembri giovane!<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/semplici-modi-per-rendere-se-stessi-una-priorita\/\" target=\"_blank\" rel=\"noopener noreferrer\">18 semplici modi per darsi una priorit\u00e0 nel modo che meritate<\/a><\/p>\n<h2 class=\"numbered-headline\">Quella persona speciale<\/h2>\n<p><em>di Richard N. Cook<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96692\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars.jpg\" alt=\"coppia che osserva le stelle di notte seduta su una panchina all&#039;aperto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-watching-the-stars-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>\u00c8 la pupilla dei miei occhi,<br \/>\nLa ragione della mia vita.<br \/>\n\u00c8 tutto ci\u00f2 che potrei desiderare.<br \/>\nA lei dono il mio cuore.<\/p>\n<p>\u00c8 per quella persona speciale<br \/>\nQueste parole che ho scritto,<br \/>\nPer ringraziarla di essere sempre<br \/>\nMia moglie e il mio migliore amico.<\/p>\n<p>Ha la volont\u00e0 di vivere fino a quando<br \/>\nL'ultimo respiro che fa.<br \/>\nC'\u00e8 l'amore nel suo cuore,<br \/>\nChe bei ricordi da creare.<\/p>\n<p>Lei \u00e8 il sole della mia mattina,<br \/>\nThe star that\u2019s in my sky,<br \/>\nE se mai dovessi perderla,<br \/>\nAllora sarei sicuramente morto.<\/p>\n<p>\u00c8 sempre al mio fianco,<br \/>\nQualunque cosa ci capiti a tiro.<br \/>\nMi conforta con il suo amore costante<br \/>\nOgni giorno.<\/p>\n<p>Porta molti fardelli,<br \/>\nE il suo cuore a volte si spezza<br \/>\nPer tutti i ringraziamenti che non riceve mai<br \/>\nE tutte le parole non dette.<\/p>\n<p>So che la sua vita non \u00e8 sua.<br \/>\nSembro sempre cos\u00ec bisognosa,<br \/>\nE chiedendole di fare un'altra cosa,<br \/>\nMi sento davvero avido.<\/p>\n<p>Come potr\u00f2 mai ringraziarla<br \/>\nPer tutto quello che ha fatto per me?<br \/>\nPosso solo darle tutto il mio cuore<br \/>\nE amarla per l'eternit\u00e0.<\/p>\n<p>Spero che quando arriver\u00e0 la fine,<br \/>\nE incontra Dio faccia a faccia,<br \/>\nLe dir\u00e0 che in Paradiso<br \/>\nHa un posto speciale.<\/p>\n<h2 class=\"numbered-headline\">Un sogno per te<\/h2>\n<p><em>di Richard N. Cook<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96698\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters.jpg\" alt=\"donna in piedi nell&#039;acqua vicino alle cascate nella foresta da sogno\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-standing-in-the-waters-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Se potessi sognare<br \/>\nIl sogno che volevo,<br \/>\nChiudevo gli occhi,<br \/>\nE sognare un sogno per voi.<\/p>\n<p>Ti darei tutto il mondo,<br \/>\nChe vi meritate,<br \/>\nE a voi darei<br \/>\nIl mio amore eterno.<\/p>\n<p>Mi assicurerei che<br \/>\nChe non sei mai stato triste<br \/>\nE niente nella tua vita<br \/>\nNon sarebbe mai successo nulla di male.<\/p>\n<p>Desidero per voi<br \/>\nTutto andrebbe per il verso giusto,<br \/>\nE sareste sempre felici,<br \/>\nOgni giorno.<\/p>\n<p>Nel mio sogno<br \/>\nRimarresti<br \/>\nAltrettanto bello<br \/>\nCome lo siete oggi.<\/p>\n<p>La vita per voi sarebbe perfetta<br \/>\nCome l'azzurro del cielo,<br \/>\nE nessuno ti far\u00e0 mai del male,<br \/>\nO addirittura farvi piangere.<\/p>\n<p>I know it\u2019s just a dream,<br \/>\nMa se i sogni potessero diventare realt\u00e0,<br \/>\nChiuderei gli occhi<br \/>\nE sognare un sogno per voi.<\/p>\n<h2 class=\"numbered-headline\">She&#8217;s My Everything<\/h2>\n<p><em>da Sconosciuto<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96702\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon.jpg\" alt=\"Coppia felice in luna di miele che si gode le acque della spiaggia\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-in-honeymoon-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>She\u2019s my morning,<br \/>\nShe\u2019s my favorite song to sing,<br \/>\nShe\u2019s the poems that I write,<br \/>\nShe\u2019s my everything<\/p>\n<p>She\u2019s my sparkle,<br \/>\nShe\u2019s my shine,<br \/>\nShe\u2019s the only thing,<br \/>\nVoglio chiamare il mio<\/p>\n<p>She\u2019s my voice,<br \/>\nShe\u2019s my ears,<br \/>\nE stare senza di lei,<br \/>\n\u00c8 una delle mie pi\u00f9 grandi paure<\/p>\n<p>She\u2019s the reason I dream,<br \/>\nShe\u2019s the reason I follow my heart,<br \/>\nShe\u2019s the reason why,<br \/>\nVoglio che questa relazione inizi<\/p>\n<p>She\u2019s my afternoon,<br \/>\nShe\u2019s my thoughts all day,<br \/>\nShe\u2019s the reason why,<br \/>\nDico le cose dolci che dico<\/p>\n<p>She\u2019s my sleepless nights,<br \/>\nShe\u2019s my soul,<br \/>\nShe\u2019s the reason why,<br \/>\nI can\u2019t keep control<\/p>\n<p>She\u2019s my heart,<br \/>\nShe\u2019s the reason I\u2019m in love,<br \/>\nShe\u2019s the reason why,<br \/>\nRingrazio Dio sopra<\/p>\n<p>She\u2019s my everyday,<br \/>\nShe\u2019s my every night,<br \/>\nE non avrei mai rinunciato a lei,<br \/>\nNon senza combattere<\/p>\n<p>She\u2019s my morning,<br \/>\nShe\u2019s my favorite song to sing,<br \/>\nShe\u2019s the poems that I write,<br \/>\nShe\u2019s my everything.<\/p>\n<h2 class=\"numbered-headline\">Mia moglie<\/h2>\n<p><em>di Andre Cardenas<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96705\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands.jpg\" alt=\"coppia che si tiene per mano nel parco sotto un albero\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-holding-hands-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mano nella mano camminiamo insieme,<br \/>\nGod\u2019s grace warms us from above.<br \/>\nIt\u2019s him I thank each day I wake<br \/>\nper avermi benedetto con tutto il tuo amore.<\/p>\n<p>Il sole del mattino<br \/>\ne l'uccello che canta la mia canzone.<br \/>\nIn questa vita, quando sono in difficolt\u00e0,<br \/>\nthrough God, it\u2019s you who keeps me strong.<\/p>\n<p>Il vento sotto le mie ali<br \/>\nmentre quest'aquila spicca il volo.<br \/>\nVoi siete le stelle che illuminano il mio cielo<br \/>\nnell'oscurit\u00e0 della notte.<\/p>\n<p>La madre dei miei figli<br \/>\ne l'aria che mi d\u00e0 la vita.<br \/>\nMy truest friend of all\u2026<br \/>\nil mio cuore, la mia anima, mia moglie.<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/friendship\/amicizie-inopportune-da-sposati\/\" target=\"_blank\" rel=\"noopener noreferrer\">Amicizie inappropriate quando si \u00e8 sposati: Sono \"solo amici\"?<\/a><\/p>\n<h2 class=\"numbered-headline\">We&#8217;re Good, I Promise<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96719\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter.jpg\" alt=\"uomo che legge una lettera sorridendo e seduto sul divano sorridendo\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/man-reading-a-letter-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Devo ricordare che il vero amore \u00e8 forte e duraturo,<br \/>\nMa \u00e8 vero, ci sono momenti in cui i forti hanno bisogno di essere rassicurati.<\/p>\n<p>You write to me and say, \u201cDanny, everything is fine, please don\u2019t worry.\u201d Thank you.<br \/>\nTi amo tanto e ti ringrazio per aver trovato il tempo di dirmi che anche tu mi ami.<\/p>\n<p>You write to me and say, \u201cWe\u2019re good, I promise.\u201d I hope you know how much that means to me.<br \/>\nLa nostra vita insieme sar\u00e0 il tuo piacere. Ti dar\u00f2 tutto il mio amore, la mia devozione e l'attenzione che vedrai.<\/p>\n<p>Quando eravamo giovani ci concedevamo delle passeggiate nel parco.<br \/>\nMano nella mano, cos\u00ec felici insieme di camminare nel buio.<\/p>\n<p>Abbiamo amato in modo cos\u00ec puro, onesto e vero.<br \/>\nHo ringraziato Dio, allora come oggi, per avermi dato te.<\/p>\n<p>Abbiamo amato la vita e l'altro, ci siamo promessi la nostra devozione per sempre.<br \/>\nEravamo cos\u00ec felici, cos\u00ec affettuosi e sempre insieme.<\/p>\n<p>All'epoca non avevamo molte cose o soldi,<br \/>\nMa ho avuto la vita migliore; mia moglie era la mia migliore amica.<\/p>\n<p>We had love and we had each other; you were and are God\u2019s gift and my treasure.<br \/>\nAllora come oggi stare sdraiati sul divano mentre ti addormenti tra le mie braccia \u00e8 il mio piacere.<\/p>\n<p>Sono le cose semplici che significano tanto,<br \/>\nSemplice come sentire il tuo tocco.<\/p>\n<p>Ora, dopo tutti questi anni, mi sono innamorato di te.<br \/>\nSono un uomo molto benedetto e Dio mi ha benedetto; so che \u00e8 vero.<\/p>\n<p>Ogni giorno mi sveglio e capisco cosa voglio fare.<br \/>\nVoglio trascorrere ogni giorno della mia vita dedicandomi a te e amandoti.<\/p>\n<p>Voglio vivere nuove avventure nella vita; sapete che \u00e8 vero,<br \/>\nMa non voglio fare nulla che non includa voi.<\/p>\n<p>Amiamo l'oggi come mai prima d'ora,<br \/>\nPerch\u00e9 ogni giorno ti amo molto di pi\u00f9.<\/p>\n<p>Siete cos\u00ec belli, ogni giorno di pi\u00f9.<br \/>\nLa vostra bellezza \u00e8 pi\u00f9 di ieri.<\/p>\n<p>Sei maturata da una bella e giovane sposa<br \/>\nA una bella donna matura con amore e orgoglio.<\/p>\n<p>Non abbiamo pi\u00f9 la giovent\u00f9 dalla nostra parte.<br \/>\nOur age is something that we much longer can\u2019t hide.<\/p>\n<p>Il mio amore per te si \u00e8 rafforzato nel corso degli anni.<br \/>\nIl tuo amore mi d\u00e0 forza, cos\u00ec quando invecchiamo non ho paura.<\/p>\n<p>Ti amo e spero che tu sappia che sei la mia benedizione, mia moglie.<br \/>\nMi impegno ad amarti e a prendermi cura di te per il resto della mia vita.<\/p>\n<h2 class=\"numbered-headline\">Un dono di Dio<\/h2>\n<p><em>da Dino<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96725\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple.jpg\" alt=\"coppia di bambini in attesa abbracciati e in piedi contro il muro bianco\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/expecting-baby-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Cos\u00ec giovane, cos\u00ec fresco, cos\u00ec nuovo<br \/>\nL'amore e la passione che ho provato per te.<br \/>\nTi ho amato cos\u00ec tanto e tu hai detto s\u00ec<br \/>\nUn dono di Dio, sono stato benedetto<\/p>\n<p>Una donna bellissima con un cuore cos\u00ec vero<br \/>\nL'amore e la passione che ancora provo per te<br \/>\nPer tutta la gravidanza, mentre porti in grembo nostro figlio<br \/>\nA gift from God, I\u2019m the lucky one<\/p>\n<p>Una madre e una moglie meravigliosa<br \/>\nL'amore e la passione per tutta la vita<br \/>\nSei davvero un dono di Dio<br \/>\nUna benedizione dall'alto per l'uomo pi\u00f9 fortunato in assoluto<\/p>\n<h2 class=\"numbered-headline\">Il senso dell'amore<\/h2>\n<p><em>di William Wilson<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96733\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple.jpg\" alt=\"vista dall&#039;alto di una giovane coppia che si abbraccia nel letto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/top-view-of-young-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>L'amore non \u00e8 qualcosa che si vede.<br \/>\nSignifica tutto per me.<br \/>\nIt\u2019s needing to have you in my life,<br \/>\nTanto che ti ho fatto diventare mia moglie.<\/p>\n<p>L'amore non \u00e8 qualcosa che si sente dire.<br \/>\nIt\u2019s always wanting to have you near.<br \/>\nIt\u2019s needing to feel your lips each day<br \/>\nTante cose che nessuna parola potrebbe mai dire.<\/p>\n<p>L'amore non \u00e8 qualcosa che si assapora.<br \/>\nIt\u2019s never letting it go to waste.<br \/>\nIt\u2019s needing to see you even when we fight,<br \/>\nSo much or I\u2019ll miss you day and night.<\/p>\n<p>L'amore non si tocca.<br \/>\nIt\u2019s knowing that you mean so much.<br \/>\nIt\u2019s needing your skin when I\u2019m in bed,<br \/>\nCos\u00ec tanto da farmi perdere la testa.<\/p>\n<p>L'amore non \u00e8 qualcosa che si annusa.<br \/>\nIt\u2019s something that you\u2019re proud to tell.<br \/>\nIt\u2019s needing to always make you smile,<br \/>\nTanto da rendere la mia vita degna di essere vissuta.<\/p>\n<h2 class=\"numbered-headline\">Una bella resa<\/h2>\n<p><em>di Miles Fredette<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96736\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/silhouette-of-a-couple.jpg\" alt=\"silhouette di una coppia con il naso all&#039;ins\u00f9 e che si tiene per mano sulla spiaggia durante il tramonto\" width=\"800\" height=\"533\"><\/p>\n<p>We\u2019re alongside the ocean, the gentle sea breeze is flowing through your hair revealing your sapphire eyes<br \/>\nle nostre mani sono unite e abbracciate come se fosse una vita d'amore<br \/>\nil sole sta lentamente calando, lasciando spazio a un nuovo giorno<br \/>\nit feels as if we\u2019re being born again, given a new chance<br \/>\na chance to learn of mistakes past and generate an abundance of love in which we\u2019ve never felt<br \/>\nil cielo \u00e8 uno splendido spettacolo di colori, di una bellezza inimmaginabile<br \/>\nun raggio di sole che attraversa una nuvola di passaggio e ci trova<br \/>\nfissi il mare ormai arancione, l'oceano si riflette nei tuoi occhi mentre avvicino il tuo corpo al mio.<br \/>\nI feel as if there\u2019s no one else<br \/>\nnell'universo tranne voi e io, poich\u00e9 tutti i sensi vengono meno<br \/>\nit\u2019s as if we were meant to be here at this moment in time together<br \/>\nsiamo uniti dall'amore e dalla lussuria e spero che, proprio come il sole, un giorno cadremo insieme per far posto a una nuova vita e a nuovi giorni.<br \/>\nuna bella resa<\/p>\n<h2 class=\"numbered-headline\">Un semplice bouquet<\/h2>\n<p><em>da Chris<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96738\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower.jpg\" alt=\"donna che riceve un mazzo di fiori dal suo uomo seduto e abbracciato su una panchina all&#039;aperto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-receiving-a-bouquet-of-flower-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mi sono fermato al negozio per comprarti un mazzo di fiori.<br \/>\nQuello che ho scoperto \u00e8 che aveva molto da dire<br \/>\nI fiori rappresentavano ciascuno una parte della nostra vita<br \/>\nE sono stati pensati per te, mia bellissima moglie.<\/p>\n<p>Quello giallo \u00e8 il nome di una bambina che conosciamo entrambi.<br \/>\nShe\u2019s pretty and sweet and always ready to go<br \/>\nCanta canzoni da bambina e ha bellissimi capelli scuri.<br \/>\nDio ci ha dato un angelo per i nostri cuori da condividere<\/p>\n<p>La rosa bianca rappresenta il bambino della nostra casa.<br \/>\nThere are days that I know he won\u2019t leave you alone<br \/>\nHe\u2019s happy and smart and full of such joy<br \/>\nWe\u2019re lucky to be blessed with such a sweet boy<\/p>\n<p>The red one\u2019s a sign of the love that WE share<br \/>\nNel corso del tempo abbiamo dimostrato quanto ci sta a cuore<br \/>\nAmiamo nei modi in cui gli altri desiderano solo<br \/>\nE sperare l'uno nell'altro con un sorriso e un bacio<\/p>\n<p>Quel nastro che tiene il bouquet in un mazzo di fiori<br \/>\nI didn\u2019t get it at first, yet it means so much<br \/>\nRappresenta il tuo amore nella nostra casa, ogni giorno.<br \/>\nCome centro della nostra famiglia in ogni modo<\/p>\n<p>This bouquet in the store, I\u2019ll just have to get<br \/>\nThe best part of this is it isn\u2019t done yet<br \/>\nCi sono pi\u00f9 fiori da aggiungere, pi\u00f9 momenti per divertirsi<br \/>\nPi\u00f9 notti piene di risate e pi\u00f9 giorni pieni di sole<\/p>\n<p>Quindi, la prossima volta che porter\u00f2 dei fiori, spero che tu sappia che<br \/>\nIl vostro amore significa per me molto di pi\u00f9 di quanto io possa mai mostrare.<\/p>\n<h2 class=\"numbered-headline\">Ti amer\u00f2 per sempre<\/h2>\n<p><em>da Sconosciuto<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96739\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap.jpg\" alt=\"donna seduta sulle ginocchia dell&#039;uomo che le tiene la vita in salotto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-sitting-on-the-lap-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ti amo profondamente,<br \/>\nTi amo cos\u00ec tanto,<br \/>\nAmo il suono della tua voce<br \/>\nE il modo in cui ci tocchiamo.<\/p>\n<p>Amo il tuo caldo sorriso<br \/>\nE il suo modo gentile e premuroso,<br \/>\nLa gioia che porti con te<br \/>\nAlla mia vita ogni giorno.<\/p>\n<p>Oggi ti amo<br \/>\nCome ho fatto fin dall'inizio,<br \/>\nAnd I\u2019ll love you forever<br \/>\nCon tutto il mio cuore.<\/p>\n<h2 class=\"numbered-headline\">Il mio primo amore<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96741\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing.jpg\" alt=\"Giovane coppia che si bacia in una fredda giornata all&#039;aperto\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/young-couple-kissing-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Pammy, sei il mio primo amore, quello che amo ancora oggi.<br \/>\nSei ancora bellissima e ho imparato ad amarti in tanti modi diversi.<\/p>\n<p>Ti amo per i tuoi modi premurosi, gentili e delicati.<br \/>\nTi amo per la tua bellezza, che migliora di giorno in giorno.<\/p>\n<p>Ti amo per i tuoi baci, il tuo tocco e i tuoi modi amorevoli.<br \/>\nHo amato ieri, oggi e lo far\u00f2 domani. Prometto che il mio amore \u00e8 qui per restare.<\/p>\n<p>Ti amo perch\u00e9 hai salvato e ti sei donato a me.<br \/>\nVi amo e vi rispetto, spero che lo vediate.<\/p>\n<p>Voglio che tu sappia che ti rispetto davvero per questo atto d'amore.<br \/>\nRicordo bene la prima volta che abbiamo fatto l'amore, sei un dono di Dio.<\/p>\n<p>Il passato \u00e8 passato, l'oggi va vissuto.<br \/>\nTi ho amato ieri e oggi, domani avr\u00f2 pi\u00f9 amore da dare.<\/p>\n<p>La vostra devozione non ha mai vacillato, il vostro amore \u00e8 cos\u00ec vero.<br \/>\nIo do la mia anima a Dio, e il mio cuore lo do a te.<\/p>\n<p>Mi sono innamorata di te la prima volta che ci siamo baciati.<br \/>\nOgni minuto che ci separa, sappi che ci manchi.<\/p>\n<p>Pammy, il mio amore per te \u00e8 puro e vero.<br \/>\nNon c'\u00e8 nessun'altra ragazza per me, perch\u00e9 posso amare solo te.<\/p>\n<p>Tu sei il mio amore, la mia gioia, la mia vita, il mio respiro, il battito del mio cuore<br \/>\nTi prego di sapere che ti amo, che ti desidero e che mi uccide quando ci separiamo.<\/p>\n<p>Prometto di darti tutto quello che ho, il mio amore per te \u00e8 infinito, tuo per tutta la vita e per l'eternit\u00e0.<br \/>\nPrometto di amarti, onorarti, custodirti, proteggerti e dedicarmi a te.<\/p>\n<p>Pammy, tu sei il mio primo amore, il mio vero amore, l'amore che prometto di proteggere e di dare tutto.<br \/>\nRingrazio Dio per il privilegio di amarvi.<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/accettare-le-persone-per-quello-che-sono\/\" target=\"_blank\" rel=\"noopener noreferrer\">Accettare le persone per quello che sono invece di cercare di cambiarle<\/a><\/p>\n<h2 class=\"numbered-headline\">Cammina nelle mie scarpe<\/h2>\n<p><em>di Steven P. Dawson<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96744\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking.jpg\" alt=\"dolce coppia che cammina con i bagagli lungo le rotaie del treno\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-walking-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Se camminaste nei miei panni per un giorno,<br \/>\nYou\u2019d know how I love you in such a way.<\/p>\n<p>You\u2019d share the aching of my heart<br \/>\nper ogni momento che trascorriamo separati.<\/p>\n<p>You\u2019d feel electricity when I touch your skin<br \/>\ne il calore che ricevo nel vederti sorridere.<\/p>\n<p>You\u2019d see me tumble into your eyes,<br \/>\ncome illuminano i cieli pi\u00f9 grigi.<\/p>\n<p>You\u2019d smell the sweetness of your aura,<br \/>\nche irradia come una flora appena colta.<\/p>\n<p>You\u2019d hear how saying three simple words<br \/>\n\u00e8 come sentire il dolcissimo canto degli uccelli.<\/p>\n<p>Se camminaste nei miei panni per il resto della vostra vita,<br \/>\nyou\u2019d know that I\u2019m thankful that you\u2019re my wife.<\/p>\n<h2 class=\"numbered-headline\">Grazie<\/h2>\n<p><em>di Michael A. Faust<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96924\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love.jpg\" alt=\"bella coppia in amore incontri all&#039;aperto abbracciando e la donna che tiene il viso dell&#039;uomo\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-in-love-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>I know it&#8217;s been a hard task,<br \/>\nle cose che vi chiediamo.<br \/>\nYou should know you&#8217;re very special<br \/>\nper tutte le cose che fate.<\/p>\n<p>I&#8217;m thankful for a wife like you;<br \/>\nnessuno potrebbe prendere il tuo posto.<br \/>\nUn cuore come il tuo per chi ha bisogno<br \/>\nis a thing one can&#8217;t replace.<\/p>\n<p>Quindi grazie ancora per la sua presenza<br \/>\ne per tutte le cose che fate.<br \/>\nNessun uomo potrebbe essere cos\u00ec fortunato<br \/>\navere un amore come te!<\/p>\n<p>Happy Mother&#8217;s Day!<\/p>\n<p>Lascia che i miei occhi siano massaggiati dalla tua bellezza.<br \/>\nLascia che il mio cuore sia riscaldato dal tuo sorriso.<br \/>\nFa' che le mie orecchie sentano sempre che mi ami.<br \/>\nLascia che le mie labbra bacino le tue per un po'.<\/p>\n<p>Let my arms hold you close when you&#8217;re sad.<br \/>\nLet my hugs make you warm when you&#8217;re cold.<br \/>\nChe il mio amore duri quanto l'eternit\u00e0.<br \/>\nIn questo modo non invecchieremo mai.<\/p>\n<p>Let me promise you&#8217;ll never be lonely.<br \/>\nPrometto di essere sempre sincero,<br \/>\nTi prego, fammi essere felice per il resto della mia vita,<br \/>\nWhen I ask you, please say, &#8220;I do.&#8221;<\/p>\n<h2 class=\"numbered-headline\">To My Wife, Chiholloli (\u201cI Love You\u201d)<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96925\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love.jpg\" alt=\"Coppia innamorata all&#039;aperto in inverno \" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-in-love-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Non conosco tutte le lingue di questo mondo.<br \/>\nNon conosco tutti i modi per dirti che ti amo, ragazza.<\/p>\n<p>Esprimer\u00f2 il mio amore con le parole e con le azioni.<br \/>\nTe lo prometto per sempre, e spero che tu lo veda.<\/p>\n<p>Your beauty is endless in my eyes, can\u2019t you see?<br \/>\nPerch\u00e9 tu sei l'unico amore per me.<\/p>\n<p>Desidero abbracciarti e toccarti durante ogni notte<br \/>\nE svegliarmi con te ogni mattina per il resto della mia vita.<\/p>\n<p>La tua onest\u00e0, il tuo amore e la tua amicizia come moglie mi procurano il pi\u00f9 grande piacere.<br \/>\nYou are my love, my wife, my best friend, and God\u2019s greatest gift to me, you are my treasure.<\/p>\n<p>Come avete cominciato a vedere, la vita scorre veloce,<br \/>\nE mentre attraversiamo il tempo il mio \u00e8 un amore che durer\u00e0.<\/p>\n<p>Mentre la vita va avanti, prometto di amarti ogni giorno con un tocco gentile,<br \/>\nPer abbracciarti, baciarti, accarezzarti, prendermi cura di te, perch\u00e9 ti amo tanto, tantissimo.<\/p>\n<p>Il tuo tocco, il tuo bacio e le tue parole d'amore per me significano tanto.<br \/>\nQuando siamo lontani, mi mancano tanto il tuo amore, i tuoi baci e il tuo tocco.<\/p>\n<p>Il tuo sorriso illumina la mia giornata, il tuo tocco riscalda la mia anima e il tuo bacio mi fa battere il cuore.<br \/>\nMia carissima Pammy, ti amo, mi manchi e ti desidero quando siamo lontani.<\/p>\n<p>Come posso dimostrarti che il mio amore \u00e8 tuo, infinito e vero?<br \/>\nCome posso dimostrarvi che vi amo e vi onoro?<\/p>\n<p>Vi sollever\u00f2 fino alle stelle.<br \/>\nDimostrer\u00f2 che il mio amore per te \u00e8 un amore senza fine.<\/p>\n<p>Non conosco tutti i modi per esprimere il mio amore per voi e per voi.<br \/>\nPrometto di dimostrare in ogni modo che il mio amore per te \u00e8 vero.<\/p>\n<p>Chiholloli translated from Chickasaw is \u201cI LOVE YOU.\u201d<br \/>\nPrego Dio che tu sappia che \u00e8 vero.<\/p>\n<h2 class=\"numbered-headline\">Ti amer\u00f2 sempre<\/h2>\n<p><em>di Richard M. Deets<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96926\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying.jpg\" alt=\"amanti della spiaggia che si godono il mare uomo che bacia la donna in costume da bagno\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beach-lovers-enjoying-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ti desidero quando appaiono schegge di luce<br \/>\nE la rugiada si unisce pigramente al cielo del mattino.<br \/>\nQuando le arie, gli uccelli che si struggono per i compagni cantano,<br \/>\nVoglio la morbidezza rilassante del tuo bacio.<\/p>\n<p>Ti desidero quando il sole centra il cielo<br \/>\nE le ombre si nascondono sotto le piante dei piedi.<br \/>\nQuando le farfalle danzano tra i petali bianchi,<br \/>\nVoglio lo scintillio dei tuoi occhi sorridenti.<\/p>\n<p>Ti desidero come la luna accoglie la notte<br \/>\nE i cieli sono inondati di stelle luminose e scintillanti.<br \/>\nQuando le candele sfarfallano il loro ultimo respiro silenzioso,<br \/>\nVoglio poi sentire il tuo tocco sensuale.<\/p>\n<p>Ti desidero quando la passione gonfia tutta la tua anima<br \/>\nE il tuo bel viso risplende di luce.<br \/>\nWhen your moist lips are full of love\u2019s desire,<br \/>\nVoglio sentire ogni pulsazione del tuo cuore.<\/p>\n<p>Vi desidero quando siete stanchi e abbattuti<br \/>\nE i cieli grigi spruzzano gocce di lacrime tristi.<br \/>\nQuando il mondo ride di ogni tuo inciampo,<br \/>\nVoglio lenire dolcemente le vostre pene.<\/p>\n<p>Desidero il tuo amore in ogni momento.<br \/>\nIl tempo aggiunge anni come la sabbia sulla spiaggia,<br \/>\nQuando sentite che la vostra bellezza sta scivolando verso il vento,<br \/>\nTi vorr\u00f2 molto pi\u00f9 di adesso.<\/p>\n<h2 class=\"numbered-headline\">Linea di vita<\/h2>\n<p><em>\u200b\u200b\u200b\u200bby Marcus Ditsworth<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96928\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple.jpg\" alt=\"immagine di una giovane coppia che si abbraccia vicino al mare\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/image-of-a-young-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Come un paracadutista ha bisogno di un paracadute,<br \/>\nCome se un cantante avesse bisogno di cantare,<br \/>\nE Dio d\u00e0 vita a tutti gli esseri viventi.<br \/>\nCome l'acqua nell'oceano<br \/>\nChe tutte le creature che nuotano hanno bisogno per sopravvivere,<br \/>\nAnd a baby\u2019s love for his mother,<br \/>\nPerch\u00e9 c'\u00e8 un luccichio nei suoi occhi.<br \/>\nCome il sole che splende sul viso,<br \/>\nGiuro che ci sono angeli in alto.<br \/>\n\u00c8 cos\u00ec che vedo il mio amore per te,<br \/>\nOra vi spiego perch\u00e9.<br \/>\nSei la mia ancora di salvezza<br \/>\nPer potermi librare in nuove cose<br \/>\nProprio come un'aquila che plana sulle sue ali.<\/p>\n<h2 class=\"numbered-headline\">L'amicizia resiste a tutto<\/h2>\n<p><em>di Patrick Evans<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96929\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day.jpg\" alt=\"romantico giorno di San Valentino fotografia di due amanti che si tengono per mano in silhouette \" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/romantic-valentines-day-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>C'\u00e8 un momento nella vita<br \/>\nQuando la persona che amerete<br \/>\nPer il resto della vita<br \/>\nEntra e cattura il cuore.<\/p>\n<p>A volte, solo a volte<br \/>\nHai ferito quella persona,<br \/>\nLi allontanate,<br \/>\nSenza volerlo,<br \/>\nMa \u00e8 cos\u00ec.<br \/>\nPensieri e azioni sbagliate.<\/p>\n<p>Perch\u00e9 lo fai,<br \/>\nSi mette a rischio quella persona.<br \/>\nThat loved one\u2026<br \/>\nSi allontanano.<br \/>\nA volte,<br \/>\nAvete paura di andare avanti dopo questo,<br \/>\nMa che scelta avete?<\/p>\n<p>Tutto quello che potete fare<br \/>\nLa speranza \u00e8 che un giorno,<br \/>\nSe quella persona \u00e8 quella giusta,<br \/>\nYou will meet in spirit and soul\u2026again.<br \/>\nMigliore. Sicuri. Felice.<\/p>\n<p>Ci si unisce di nuovo, con amicizie migliori.<br \/>\nE se, per caso<br \/>\nOgnuno di voi riceve una seconda possibilit\u00e0,<br \/>\nRicordare il passato.<br \/>\nImparare dai propri errori,<br \/>\nE non lasciare che si ripetano.<br \/>\nAnd by doing this\u2026<br \/>\nOgnuno di voi scopre Shangri-la.<br \/>\nE una vita di felicit\u00e0 vi aspetta.<\/p>\n<p>Se i baci fossero acqua,<br \/>\nI\u2019d give you the sea,<br \/>\nSe gli abbracci fossero foglie,<br \/>\nI\u2019d give you a tree,<br \/>\nSe l'amicizia fosse amore,<br \/>\nI\u2019d give you eternity.<\/p>\n<p>E se siete sinceri e leali con me,<br \/>\nLa mia amicizia e il mio amore sono<br \/>\nPer sempre.<\/p>\n<p>E ogni mattina, quando aprite gli occhi, dite a voi stessi che \u00e8 speciale.<br \/>\nOgni giorno, ogni minuto,<br \/>\nOgni secondo \u00e8 davvero un dono.<br \/>\nDance like nobody&#8217;s watching,<br \/>\nE amare come se non facesse mai male.<\/p>\n<p>It\u2019s been said\u2026true friends must always hold hands<br \/>\nPerch\u00e9 sanno che l'altra mano sar\u00e0 sempre l\u00ec.<br \/>\nLa mia mano \u00e8 per sempre tesa.<\/p>\n<h2 class=\"numbered-headline\">Neve al chiaro di luna<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96930\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers.jpg\" alt=\"coppia con irrigatori che passeggia nella notte invernale in citt\u00e0\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-with-sprinklers-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Mentre la bellezza della stagione natalizia prende vita<br \/>\nPrego per la neve e per una notte innevata illuminata dalla luna<\/p>\n<p>Non voglio essere ai tropici e camminare su una spiaggia di sabbia.<br \/>\nPreferirei camminare nella neve con te, sentendo il calore della tua mano<\/p>\n<p>Nella notte, camminando lungo un sentiero coperto dalla luce della luna e da una bellissima neve<br \/>\nCi fermavamo per ammirare la tua bellezza sotto il bagliore della luna.<\/p>\n<p>Potremmo passeggiare e parlare riflettendo su trentatr\u00e9 anni di vita sotto la luna e le stelle sopra di noi.<br \/>\nSarei nel posto in cui sono stato per tutti questi trentatr\u00e9 anni, con te e ancora innamorato.<\/p>\n<p>Apprezzerei tutto ci\u00f2 che mi circonda mentre guardo i tuoi occhi<br \/>\nRingrazierei Dio per te, amore mio, lo ringrazierei per essere cos\u00ec saggio<\/p>\n<p>Ti stringerei forte per tenerti al caldo mentre camminiamo nella notte.<br \/>\nAvere il tuo amore e te tra le mie braccia significa che tutto nella vita \u00e8 giusto<\/p>\n<p>Sentire la tua voce, vedere il tuo sorriso e ascoltarti significa per me molto di pi\u00f9 di quanto tu possa immaginare.<br \/>\nLa tua voce \u00e8 come quella di un angelo, il tuo sorriso mette calore nel mio cuore, hai un bagliore speciale<\/p>\n<p>Quest'anno prego per un regalo, come ho fatto negli anni passati<br \/>\nPrego che il nostro amore si rafforzi e duri per sempre.<\/p>\n<h2 class=\"numbered-headline\">La mia canzone<\/h2>\n<p><em>di Shelly O. Starkey<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96931\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano.jpg\" alt=\"coppia di innamorati che suona il pianoforte con la donna seduta sulle ginocchia dell&#039;uomo\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/loving-couple-playing-piano-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Se uno fosse sordo<br \/>\npossa sentire il suono della musica<br \/>\ne nelle sue vibrazioni<br \/>\nconoscere la vera sensazione della sua profondit\u00e0<\/p>\n<p>Se uno fosse muto<br \/>\npotrebbe parlare al mondo<br \/>\nattraverso il ritmo della sua danza<br \/>\ne il sorriso nei suoi occhi<\/p>\n<p>Se uno fosse cieco<br \/>\npossa assaporare i colori dell'arcobaleno<br \/>\ne sentire il loro suono discordante<br \/>\nmentre si scontrano in un prisma di luce<\/p>\n<p>In piedi tra i fiori<br \/>\nsi sente il dolce aroma della rosa<br \/>\nmentre il suo profumo si disperde nel vento<\/p>\n<p>Riesci a sentire quello che sento<br \/>\nannusare ci\u00f2 che vedo<br \/>\no toccare la luce<br \/>\nche mi risplende dalla notte<\/p>\n<p>Avete avuto, come me, la fortuna di<br \/>\nper sentire il tocco armonioso<br \/>\ndi un'altra anima che ti ama pi\u00f9 della vita<br \/>\nor taste the sweet perfection of that person\u2019s embrace<\/p>\n<p>Il suo dolce profumo ha portato luce nel mio mondo<br \/>\ne le sue tenere carezze hanno riempito il mio cuore di canzoni<\/p>\n<p>Nei miei occhi la tengo<br \/>\ne la sua voce gentile mi tocca il cuore<br \/>\ntra le sue braccia, ho conosciuto la risata<br \/>\ncon il suo sorriso, conosco la pace<\/p>\n<p>Lei \u00e8 la mia vita<br \/>\nMia moglie<br \/>\nLa mia canzone<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/aumentare-lamore-per-se-stessi-e-smettere-di-sentirsi-indesiderati\/\" target=\"_blank\" rel=\"noopener noreferrer\">Modi potenti per aumentare l'amore per se stessi e smettere di sentirsi indesiderati<\/a><\/p>\n<h2 class=\"numbered-headline\">Sentimenti e pensieri<\/h2>\n<p><em>di Thomas Kachepa-Sanderson<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96932\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man.jpg\" alt=\"giovane uomo deliziato che parla al telefono cellulare mentre tiene in mano una tazza di caff\u00e8 al mattino\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/delighted-young-man-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Quando mi sveglio<br \/>\nAl mattino,<br \/>\nSento e penso<br \/>\nTante cose.<\/p>\n<p>Pensieri di rabbia<br \/>\nPensieri di aggressione,<br \/>\nPensieri su come<br \/>\nPosso sconfiggere la depressione.<\/p>\n<p>Molte persone qui<br \/>\nBut I can\u2019t help feeling lonely.<br \/>\nSix months I\u2019m living here,<br \/>\nNon ci si sentir\u00e0 mai a casa.<\/p>\n<p>Dovrei ridere?<br \/>\nDevo sorridere?<br \/>\nDura solo<br \/>\nPer un po'.<\/p>\n<p>Ma poi il pensiero di vederti<br \/>\nMi fa impazzire,<br \/>\nE il pensiero di vedere<br \/>\nIl nostro bambino non ancora nato.<\/p>\n<p>La sensazione di<br \/>\nEccitazione e gioia<br \/>\nRiempie il mio cuore,<br \/>\nI couldn\u2019t be happier.<\/p>\n<p>Parlo con te<br \/>\nIn rete e al telefono,<br \/>\nPensare sempre<br \/>\nDi tornare a casa.<\/p>\n<p>Come sta mia moglie?<br \/>\nCome se la cava?<br \/>\nAlla donna che amo,<br \/>\nMy life I\u2019m devoting.<\/p>\n<p>Quando so che stai bene<br \/>\nE tu e Bump state bene,<br \/>\nIl mio sorriso diventa pi\u00f9 grande<br \/>\nOgni giorno.<\/p>\n<p>Il modo in cui si cammina,<br \/>\nIl tuo odore,<br \/>\nPer sentire la tua voce,<br \/>\nI\u2019m under your spell.<\/p>\n<p>Voi fate in modo che tutto<br \/>\nVenire alla vita.<br \/>\nSorrido e basta<br \/>\nAnd thank God you\u2019re my wife.<\/p>\n<p>What I\u2019m trying to say<br \/>\nAttraverso tutto questo<br \/>\nSei tu che rendi la mia vita<br \/>\nUna beatitudine vivente.<\/p>\n<p>Grazie.<\/p>\n<h2 class=\"numbered-headline\">Buon anniversario di matrimonio<\/h2>\n<p><em>da Shishir<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96933\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary.jpg\" alt=\"Coppia che festeggia l&#039;anniversario all&#039;aria aperta, brindando con i bicchieri di vino\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-celebrating-anniversary-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>We\u2019ve been married for the last fifteen years<br \/>\nIl vostro ruolo di moglie merita tre applausi<br \/>\nLa nostra famiglia ha ricevuto le vostre cure complete<br \/>\nYou do everything for the kids\u2019 welfare<br \/>\nL'amore verso la nuova fase ci porta ora<br \/>\nAugurandovi un felice anniversario di matrimonio<\/p>\n<p>Insieme a voi, mi sento in una zona sicura<br \/>\nYou are our family\u2019s strong backbone<br \/>\nPrego Dio di darvi una buona salute<br \/>\nChe considero la mia pi\u00f9 grande ricchezza<br \/>\nIl mio amore futuro per te non varier\u00e0 mai<br \/>\nAugurandovi un felice anniversario di matrimonio<\/p>\n<p>Il dolore e la felicit\u00e0 vanno e vengono<br \/>\nLa nostra forza reciproca non sar\u00e0 mai bassa<br \/>\nIl messaggio di pace che entrambi diffonderemo<br \/>\nE faremo del nostro meglio per rendere felici gli altri<br \/>\nTutti allora faranno festa<br \/>\nAugurandovi un felice anniversario di matrimonio<\/p>\n<p>Tutti desiderano una vita molto buona<br \/>\nQuesto \u00e8 possibile solo grazie a una buona moglie<br \/>\nChe sta sempre al tuo fianco<br \/>\nE sente che sei il suo pi\u00f9 grande orgoglio<br \/>\nPer farvi sentire come un principe Harry<br \/>\nAugurandovi un felice anniversario di matrimonio<\/p>\n<p>Oggi vi rivolgo questo appello speciale<br \/>\nYou only swim in my heart\u2019s deep sea<br \/>\nL'ingresso di altri in essa sar\u00e0 rigorosamente rifiutato.<br \/>\n\u00c8 possibile farne un uso proficuo solo<br \/>\nCredi per me solo tu sei primario<br \/>\nAugurandovi un felice anniversario di matrimonio<\/p>\n<h2 class=\"numbered-headline\">A mia moglie<\/h2>\n<p><em>di Jerry Boettcher<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96934\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating.jpg\" alt=\"bella coppia che celebra l&#039;anniversario di matrimonio su una data di cena in procinto di baciare\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/beautiful-couple-celebrating-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>In questo giorno abbiamo pronunciato le nostre promesse.<br \/>\n\u00c8 il momento di dire quanto<br \/>\nVi apprezzo molto.<\/p>\n<p>Creato da Dio solo per me,<br \/>\nYou\u2019ve done so well to make our home<br \/>\nUn luogo di nutrimento e amore.<\/p>\n<p>Smussare i miei angoli ottusi,<br \/>\nContribuite a rendere pi\u00f9 calda la nostra famiglia<br \/>\nAlle persone che ci circondano.<\/p>\n<p>Ti amo come il primo giorno,<br \/>\nAnche se sono passati molti anni<br \/>\nIn un batter d'occhio.<\/p>\n<p>Sono cos\u00ec felice di avere anni in pi\u00f9<br \/>\nTo be with you and to adore\u2026<br \/>\nTu.<\/p>\n<h2 class=\"numbered-headline\">Vi raccomando<\/h2>\n<p><em>di Richard M. Deets<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96936\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose.jpg\" alt=\"donna sognante con una rosa accanto a s\u00e9 sdraiata su un letto di lino bianco\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/dreamy-woman-with-a-rose-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Cara, a te raccomando questa rosa di velluto,<br \/>\nIn cui un modello di te stesso tendo.<br \/>\nCome il suo lungo stelo riposa nel tuo palmo,<br \/>\nCos\u00ec solo con i tuoi occhi sorridenti si annida la mia visione.<br \/>\nTenere questa dea della mistica \u00e8 la vita,<br \/>\nUn tocco di te lo \u00e8 molto di pi\u00f9, moglie mia.<br \/>\nIl profumo si assottiglia nell'aria, il colore \u00e8 vero,<br \/>\n\u00c8 vero, eppure voi siete molto pi\u00f9 speciali.<br \/>\nIl petalo \u00e8 sereno, le vostre mani non devono affaticarsi,<br \/>\nLa vostra fiducia in noi \u00e8 pi\u00f9 che mai priva di vizi.<br \/>\nYou\u2019ll deem this dear as from me you have it;<br \/>\nLa vostra fiducia \u00e8 pi\u00f9 cara perch\u00e9 la date.<br \/>\nQuesta rosa \u00e8 perfetta come il mio bacio pu\u00f2 sigillare,<br \/>\nIl tuo amore nel mio cuore eccelso scintilla.<br \/>\nBut this as all aspects peels in love\u2019s sight,<br \/>\nMentre tu, moglie mia, eccedi in ogni diritto.<\/p>\n<h2 class=\"numbered-headline\">Le gioie di essere marito e moglie<\/h2>\n<p><em>di Danny Blackburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96937\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren.jpg\" alt=\"coppia e nipoti seduti sui prati del parco a godersi la compagnia\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-and-grandchildren-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>A 16 anni eri cos\u00ec bella, piena di vita e di avventura.<br \/>\nEri una ragazza, ti comportavi come una signora che era una donna, eri cos\u00ec matura.<\/p>\n<p>A 16 anni sei stata la mia sposa, insieme siamo stati sempre e anche nei nostri cuori.<br \/>\nA volte saltavo il lavoro per stare a casa con te solo per stare insieme; non riuscivo a sopportare che ci separassimo.<\/p>\n<p>Ci siamo sposati cos\u00ec giovani e gli altri pensavano che non avessimo idea di cosa fosse la vita.<br \/>\nLe nostre vite erano semplici, avevamo l'amore e l'altro, sapevamo di potercela fare senza dubbio.<\/p>\n<p>Non vedevamo l'ora che arrivasse il venerd\u00ec sera, per passare la maggior parte del tempo seduti ad amarci.<br \/>\nCi eravamo sposati giovani ed eravamo sulla buona strada per capire che di l\u00ec a poco io sarei diventato padre e tu madre.<\/p>\n<p>Ti ho osservato mentre il tuo corpo cambiava, vedendoti sempre pi\u00f9 bella ogni giorno.<br \/>\nAvevi l'anima di una madre premurosa, l'amore che mostravi per un bambino non ancora nato in modo molto premuroso.<\/p>\n<p>Avevi 16 anni, eri cos\u00ec bella e presto saresti diventata madre, cos\u00ec giovane eppure saggia oltre i tuoi anni.<br \/>\nSei stata incredibilmente perfetta in tutto ci\u00f2 che hai fatto per quel bambino e per tuo marito, non hai mai espresso paura.<\/p>\n<p>Ha affrontato la maternit\u00e0 con una dedizione incredibile e ha amato quel bambino con tanta passione.<br \/>\nEri cos\u00ec giovane e ancora oggi posso dire di non aver mai visto una madre con una compassione pi\u00f9 grande.<\/p>\n<p>Abbiamo avuto tre figli in tutto, abbiamo dato a tutti loro e abbiamo cercato di dare loro una buona vita.<br \/>\nWe together raised our children who in all can\u2019t complain because you did all you could to make it nice.<\/p>\n<p>Ora abbiamo dei nipoti che i nostri figli devono crescere e far vivere,<br \/>\nQuindi ora sento che dovremmo tornare al punto di partenza di 30 anni fa: vuoi essere mia moglie?<\/p>\n<p>Quello che sto cercando di dire \u00e8 che siamo stati presenti per tutti gli altri, cos\u00ec giovani nella nostra vita.<br \/>\nNon ci sono molte cose che cambierei, tranne il fatto che ora credo sia giunto il momento di scoprire le gioie dell'essere marito e moglie.<\/p>\n<p>A te dedico la mia vita, a te dedico il mio cuore, a te prometto di custodire e tenere al di sopra di tutti gli altri.<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/30-giorni-di-sfida-allamore-per-se-stessi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sfida di 30 giorni per l'amore di s\u00e9: diventare la versione migliore di se stessi<\/a><\/p>\n<h2 class=\"numbered-headline\">Anime intrecciate<\/h2>\n<p><em>di Allen Ashburn<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96938\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night.jpg\" alt=\"coppia che esce di notte all&#039;aperto uomo che bacia la guancia della donna\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-at-night-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Le anime si intrecciano in un unico cuore<br \/>\nSalda la giuntura, delle due che abbiamo usato per essere<br \/>\nMani tenacemente strette<br \/>\nI sogni si intrecciano in armonia<br \/>\nBellezza seducente<br \/>\nPersi in quegli occhi<br \/>\nDi bronzo fiammeggiante<br \/>\nLeaves\u2019 of autumn full of envy<br \/>\nLabbra glassate di passione<br \/>\nLove\u2019s honeyed nectar,<br \/>\nCaramelle il tuo bacio<br \/>\nImpulso appassionato,<br \/>\nUn'ardente serenata di gioia febbrile<br \/>\nQuesto ha stuzzicato l'appetito<br \/>\nDesidera l'elisir del tuo sudore<br \/>\nPerline sul tuo collo profumato<br \/>\nImmagini inebrianti,<br \/>\nDanzando nella mia mente<br \/>\nYesterday\u2019s dreams,<br \/>\nTomorrow\u2019s fantasy<br \/>\nToday\u2019s reality<br \/>\nLe corde del cuore strimpellate dolcemente<br \/>\nDichiara questa deliziosa canzone<br \/>\nTrabocca la sorgente<br \/>\nDi amore devoto!<\/p>\n<h2 class=\"numbered-headline\">All'ombra del tuo caldo amore<\/h2>\n<p><em>di Paul Holmes<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96939\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man.jpg\" alt=\"donna che abbraccia uomo\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/woman-embracing-man-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>All'ombra del tuo caldo amore<br \/>\nMi sento cos\u00ec al sicuro e protetta,<br \/>\nE le tue mani morbide e premurose<br \/>\nIncoraggiatemi a resistere con coraggio.<br \/>\nI vostri sorrisi leniscono e alleviano il dolore<br \/>\nDi un altro giorno buio e solitario;<br \/>\nL'arcobaleno appare tra la pioggia,<br \/>\nIl mio dolore si scioglie altrettanto rapidamente.<br \/>\nUn bagliore rassicurante nei tuoi occhi<br \/>\nMi dice che lei capisce<br \/>\nLe vie complicate dei miei sospiri<br \/>\nNasce da pensieri veramente grandiosi.<br \/>\nContinuo a guardare il tuo volto<br \/>\nE ottenere un cuore tranquillo, mio dolce conforto.<\/p>\n<h2 class=\"numbered-headline\">Senza di te<\/h2>\n<p><em>di Alon Calinao Dy<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96940\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors.jpg\" alt=\"coppia che si incontra al chiuso seduta vicino alla parete di vetro\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/couple-dating-indoors-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ti amo,<br \/>\nI can\u2019t think of a better way<br \/>\nTrascorrere la mia vita<br \/>\nPer stare con voi ogni giorno.<br \/>\nPenso a te ogni minuto.<br \/>\nSpero che pensiate a me.<br \/>\nThere\u2019s no other place,<br \/>\nPreferirei esserlo.<br \/>\nSolo uno sguardo al tuo viso,<br \/>\nTu rendi la mia vita completa.<br \/>\nLo rendete semplice e facile.<br \/>\nTi amo, bambino mio.<br \/>\nDon\u2019t ever leave me.<br \/>\nI don\u2019t want to be alone.<br \/>\nI couldn\u2019t survive without you.<br \/>\nI think I\u2019d die out on my own<br \/>\n\u2018Cause I don\u2019t know what else to do<br \/>\nWithout you\u2026<\/p>\n<h2 class=\"numbered-headline\">Il mio desiderio di te<\/h2>\n<p><em>di David Yearwood<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96941\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight.jpg\" alt=\"coppia d&#039;amore al chiaro di luna e cielo stellato abbracciata\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/love-couples-under-the-moonlight-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ti desidero quando appare la luce del mattino,<br \/>\ne la rugiada si unisce pigramente al cielo del mattino.<br \/>\nTutti gli uccelli iniziano ad accoppiarsi e a cantare,<br \/>\nVoglio il tuo bacio mentre ti sdrai in silenzio.<\/p>\n<p>Ti desidero quando il sole entra nel cielo<br \/>\nE la luce del mattino appare dolcemente.<br \/>\nQuando le farfalle danzano tra i petali bianchi,<br \/>\nVoglio la morbidezza della tua pelle e il tuo piacere.<\/p>\n<p>Ti desidero come la luna accoglie la notte<br \/>\nE i cieli sono inondati di stelle scintillanti.<br \/>\nQuando le candele sfarfallano la loro luce sensuale,<br \/>\nVoglio poi sentire il tuo tocco sensuale.<\/p>\n<p>Ti desidero quando la passione muove la mia anima,<br \/>\ne il tuo bel viso risplende luminoso e chiaro.<br \/>\nWhen your moist lips touch mine, with love\u2019s desire,<br \/>\nVoglio sentire ogni pulsazione del tuo cuore...\".<\/p>\n<p>Ti desidero quando vedo il tuo corpo sexy,<br \/>\ne la luce della luna lascia il posto a quella del mattino.<br \/>\nQuando ti sdrai con il sole che ti illumina,<br \/>\nVoglio sentire la tua pelle contro la mia...\".<\/p>\n<p>Ti desidero in ogni momento,<br \/>\ncome gli anni a venire sono come la sabbia sulla spiaggia.<br \/>\nTi voglio cos\u00ec tanto, mentre i miei giorni diventano notte,<br \/>\ni miei desideri dureranno come i cieli!<\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/life\/come-distaccarsi-emotivamente-da-qualcuno\/\" target=\"_blank\" rel=\"noopener noreferrer\">Come staccarsi emotivamente da qualcuno: 14 passi per il successo<\/a><\/p>\n<h2 class=\"numbered-headline\">Amore angelico<\/h2>\n<p><em>di David Carlson<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96943\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman.jpg\" alt=\"bella donna bionda con gli occhi azzurri sdraiata su letto e cuscini bianchi\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/pretty-blonde-woman-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ho fatto l'amore con un angelo.<br \/>\nSo come si sente il paradiso.<br \/>\nHo baciato la bocca di un angelo.<br \/>\nSo che sapore ha il paradiso.<br \/>\nMi strinse forte tra le braccia.<br \/>\nSono morto nel suo abbraccio.<br \/>\nSe questo \u00e8 davvero il paradiso.<br \/>\nPrendi la mia vita oggi.<\/p>\n<h2 class=\"numbered-headline\">Il mio desiderio di Natale sei tu<\/h2>\n<p><em>di John Anthony Lopiccolo<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96944\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift.jpg\" alt=\"dolce coppia che apre un regalo in casa con un albero di Natale alle spalle\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/sweet-couple-opening-gift-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Buon Natale, tesoro<br \/>\nun altro anno \u00e8 passato<br \/>\ninnamorarsi sempre di pi\u00f9 di te<br \/>\nil mio cuore \u00e8 come una massa<br \/>\nGentilezza, amore e pazienza<br \/>\n3 cose che ho imparato da te<br \/>\nLa pazienza \u00e8 il numero uno<br \/>\nyou\u2019ve taught this through and through<br \/>\nGrazie per i ricordi<br \/>\ntanti ne abbiamo fatti<br \/>\nalcuni cattivi, per lo pi\u00f9 buoni<br \/>\nbut none I\u2019ll ever trade<br \/>\nGuarda dentro il mio cuore<br \/>\nit\u2019s filled through and through<br \/>\nL'unica cosa che voglio per Natale<br \/>\nPu\u00f2 venire solo da te<br \/>\nla cosa pi\u00f9 importante che posso darvi<br \/>\ncan\u2019t buy a single thing<br \/>\ntempo, ascolto e amore<br \/>\nsulla mano sinistra un anello<br \/>\nun simbolo del mio impegno<br \/>\nnon il valore dell'oro<br \/>\nSar\u00f2 ancora al tuo fianco<br \/>\nse l'anello viene venduto<br \/>\nsi spera che abbiate capito<br \/>\nil mio desiderio si \u00e8 avverato<br \/>\nBuon Natale, tesoro<br \/>\nIl mio desiderio di Natale sei tu<\/p>\n<p>Ti amo.<\/p>\n<p><em><strong><span style=\"font-size: 24pt;\">Poesie d'amore brevi e belle per la moglie<\/span><\/strong><\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96945\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple.jpg\" alt=\"giovane coppia felice che si gode la spiaggia uomo che bacia la donna\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-young-couple-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>1. Nessun uomo non noter\u00e0 la bellezza in voi<br \/>\nIt\u2019s like you are an angel out of the blue<br \/>\nIl vostro volto non pu\u00f2 far decollare mille navi<br \/>\nBut it\u2019s your heart and soul that is for keeps.<\/p>\n<p>Mi ipnotizzi con il tuo sorriso innocente<br \/>\nBut it\u2019s your eyes that had me there for a while<br \/>\nCome vorrei che tutti apprezzassero<br \/>\nLa bellezza in te che non \u00e8 mai da odiare<\/p>\n<p><em>\u2014Anonymous<\/em><\/p>\n<p>2. In sogni oziosi di tanto tempo fa,<br \/>\nHo immaginato il mio vero amore;<br \/>\nUna coppia perfetta, un'anima gemella,<br \/>\nUn angelo dall'alto.<\/p>\n<p>Now you\u2019re here, and now I know<br \/>\nIl nostro amore rester\u00e0, prosperer\u00e0 e crescer\u00e0.<\/p>\n<p><em>\u2014Joanna Fuchs<\/em><\/p>\n<p>3. Non ho mai conosciuto la felicit\u00e0;<br \/>\nI didn\u2019t think dreams came true;<br \/>\nI couldn\u2019t really believe in love,<br \/>\nFinch\u00e9 non ti ho incontrato.<\/p>\n<p><em>\u2014Joanna Fuchs<\/em><\/p>\n<p>4. Le labbra sono morbide e rosse.<br \/>\nIl pensiero di baciarti mi \u00e8 rimasto in testa.<br \/>\nLa vostra bellezza cos\u00ec luminosa e calda,<br \/>\nche risplende attraverso la tempesta pi\u00f9 buia.<\/p>\n<p>I tuoi occhi brillano come stelle nel cielo notturno.<br \/>\nQuando li guardo, mi sembra di volare in alto.<br \/>\nIl mio amore per te \u00e8 puro e vero.<br \/>\nNon smetto mai di pensare a te.<\/p>\n<p>The sound of your voice saying, &#8220;I love you,&#8221; makes my heart pound,<br \/>\nbecause I know my one and only I&#8217;ve truly found.<br \/>\nPrometto di amarti per ogni istante di tutta l'eternit\u00e0,<br \/>\ne quando tutto il resto si sgretoler\u00e0, non lo far\u00f2 mai.<\/p>\n<p>Sono la vostra armatura per proteggervi dal male,<br \/>\ncome tu sei per me, un portafortuna.<br \/>\nPerch\u00e9 tu sei il mio cuore, la mia anima.<br \/>\nPiccola, tu sei tutto il mio mondo.<\/p>\n<p><em>\u2014Jamie Emms<\/em><\/p>\n<p>5. You&#8217;re one in a million, my most special one;<br \/>\nIl vostro sorriso radioso \u00e8 luminoso come il sole;<br \/>\nYou&#8217;re smart and caring and have many great charms,<br \/>\nAnd my heart really sings when you&#8217;re wrapped in my arms.<\/p>\n<p>I&#8217;m happy you chose me from all of the rest,<br \/>\nAnd I&#8217;m proud &#8217;cause I know that I got the best.<br \/>\nYou&#8217;re so cute and sweet, and you glow like a pearl;<br \/>\nTi amo cos\u00ec tanto, mia meravigliosa ragazza!<\/p>\n<p><em>\u2014Karl Fuchs<\/em><\/p>\n<p>Vedi anche: <a href=\"https:\/\/herway.net\/it\/relationship\/la-relazione-epistolare-riporta-in-auge-il-romanticismo-della-vecchia-scuola\/\" target=\"_blank\" rel=\"noopener noreferrer\">Relazione epistolare: 6 motivi per riportare in auge il romanticismo della vecchia scuola<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96946\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing.jpg\" alt=\"coppia felice che si bacia all&#039;aperto coprendosi il viso con un cappello\" width=\"800\" height=\"533\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing.jpg 800w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing-300x200.jpg 300w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing-768x512.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing-150x100.jpg 150w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/happy-couple-kissing-720x481.jpg 720w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>Ed eccola qui. Una sentita raccolta di poesie d'amore per la moglie a cui nessuna donna potrebbe rimanere indifferente.<\/p>\n<p>So che le citazioni d'amore e le poesie dolci non possono essere l'unica base di un matrimonio felice. Ma possono sicuramente contribuire alla sua longevit\u00e0 e al suo successo.<\/p>\n<p>You can send these romantic love poems for a wife as cute text messages she won&#8217;t see coming, via her personal email, or write them down and send it to her the old fashioned way!<\/p>\n<p><strong>The choice is yours, but one thing&#8217;s for sure: Wife poems will <em>sempre<\/em> be \u00e0 la mode.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-96948\" src=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest.jpg\" alt=\"Una raccolta di poesie d&#039;amore incredibilmente romantiche per la moglie\" width=\"1000\" height=\"1500\" srcset=\"https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest.jpg 1000w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest-200x300.jpg 200w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest-683x1024.jpg 683w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest-768x1152.jpg 768w, https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife-Pinterest-150x225.jpg 150w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Have you ever considered how special love poems for wife can be? Not only do they scream I love you, but they also show your wife that you&#8217;re still a romantic at heart! To help you find just the right words, I&#8217;ve compiled a collection of romantic poems, short love poems, I love you poems&#8230;<\/p>","protected":false},"author":41,"featured_media":96947,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[29654],"tags":[],"class_list":["post-96591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paragraphs"],"taxonomy_info":{"category":[{"value":29654,"label":"paragraphs"}]},"featured_image_src_large":["https:\/\/herway.net\/wp-content\/uploads\/2020\/08\/A-Collection-Of-Incredibly-Romantic-Love-Poems-For-Wife.jpg",800,533,false],"author_info":{"display_name":"Martha Sullivan","author_link":"https:\/\/herway.net\/it\/author\/martha-sullivan\/"},"comment_info":0,"category_info":[{"term_id":29654,"name":"paragraphs","slug":"paragraphs","term_group":0,"term_taxonomy_id":29654,"taxonomy":"category","description":"Are you in search of the right words to express yourself? Here are the best paragraphs on love, best friends, comebacks, captions, etc.","parent":29651,"count":44,"filter":"raw","cat_ID":29654,"category_count":44,"category_description":"Are you in search of the right words to express yourself? Here are the best paragraphs on love, best friends, comebacks, captions, etc.","cat_name":"paragraphs","category_nicename":"paragraphs","category_parent":29651}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/posts\/96591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/comments?post=96591"}],"version-history":[{"count":0,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/posts\/96591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/media\/96947"}],"wp:attachment":[{"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/media?parent=96591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/categories?post=96591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herway.net\/it\/wp-json\/wp\/v2\/tags?post=96591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}